{"id":12661,"date":"2022-06-10T10:50:47","date_gmt":"2022-06-10T08:50:47","guid":{"rendered":"https:\/\/cielavillage.fr\/?page_id=12661"},"modified":"2026-07-03T13:28:04","modified_gmt":"2026-07-03T11:28:04","slug":"offerte-campeggi-per-comitati-aziendali","status":"publish","type":"page","link":"https:\/\/cielavillage.fr\/it\/offerte-campeggi-per-comitati-aziendali\/","title":{"rendered":"Scopri le nostre offerte CSE"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Regala ai tuoi collaboratori una vacanza indimenticabile!<br\/><br\/>Vuoi proporre ai tuoi dipendenti un&#8217;offerta vacanze interessante a tariffe agevolate?<\/p>\n\n<p class=\"wp-block-paragraph\">Ciela Village affianca i <strong>Comitati Sociali ed Economici (CSE)<\/strong>, <strong>i COS<\/strong> e <strong>le associazioni del personale<\/strong> nell&#8217;organizzazione di offerte vacanze interessanti per i loro dipendenti e beneficiari.<\/p>\n\n<p class=\"wp-block-paragraph\">Con <strong>24 campeggi da 3 a 5 stelle<\/strong>, situati in riva al mare, in riva al lago, in campagna o in montagna, ti proponiamo soggiorni <strong>nel cuore delle pi\u00f9 belle destinazioni<\/strong> francesi.<\/p>\n\n<p class=\"wp-block-paragraph\">La nostra promessa? Rendere le vacanze alla portata di tutti grazie a offerte esclusive, alloggi di qualit\u00e0 ed esperienze indimenticabili per tutta la famiglia. <\/p>\n\n<div style=\"height:45px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full is-style-default\"><img decoding=\"async\" width=\"800\" height=\"533\" data-id=\"17682\" src=\"https:\/\/cielavillage.fr\/wp-content\/uploads\/2023\/10\/Le-parc-aquatique-du-camping-Terra-Verdon-a-Castellane.jpg\" alt=\"Campeggio Castellane Ciela Village Terra Verdon - parco acquatico\" class=\"wp-image-17682\" srcset=\"https:\/\/cielavillage.fr\/wp-content\/uploads\/2023\/10\/Le-parc-aquatique-du-camping-Terra-Verdon-a-Castellane.jpg 800w, https:\/\/cielavillage.fr\/wp-content\/uploads\/2023\/10\/Le-parc-aquatique-du-camping-Terra-Verdon-a-Castellane-300x200.jpg 300w, https:\/\/cielavillage.fr\/wp-content\/uploads\/2023\/10\/Le-parc-aquatique-du-camping-Terra-Verdon-a-Castellane-768x512.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption class=\"wp-element-caption\"><strong>Campeggio Terra Verdon<\/strong><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"800\" height=\"599\" data-id=\"25782\" src=\"https:\/\/cielavillage.fr\/wp-content\/uploads\/2024\/11\/059-Camping-Occitanie-Beau-Rivage-Ciela-Village-Drone-3.jpg\" alt=\"Vista aerea dal drone del campeggio Beau Rivage Ciela Village nel Vaucluse\" class=\"wp-image-25782\" srcset=\"https:\/\/cielavillage.fr\/wp-content\/uploads\/2024\/11\/059-Camping-Occitanie-Beau-Rivage-Ciela-Village-Drone-3.jpg 800w, https:\/\/cielavillage.fr\/wp-content\/uploads\/2024\/11\/059-Camping-Occitanie-Beau-Rivage-Ciela-Village-Drone-3-300x225.jpg 300w, https:\/\/cielavillage.fr\/wp-content\/uploads\/2024\/11\/059-Camping-Occitanie-Beau-Rivage-Ciela-Village-Drone-3-768x575.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption class=\"wp-element-caption\"><strong>Campeggio Beau Rivage<\/strong><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"800\" height=\"533\" data-id=\"26366\" src=\"https:\/\/cielavillage.fr\/wp-content\/uploads\/2024\/11\/141-Camping-Drome-Lac-Bleu-Ciela-Lac.jpg\" alt=\"Campeggio Le Lac Bleu Ciela Village, Dr&#xF4;me, Ch&#xE2;tillon-en-Diois\" class=\"wp-image-26366\" srcset=\"https:\/\/cielavillage.fr\/wp-content\/uploads\/2024\/11\/141-Camping-Drome-Lac-Bleu-Ciela-Lac.jpg 800w, https:\/\/cielavillage.fr\/wp-content\/uploads\/2024\/11\/141-Camping-Drome-Lac-Bleu-Ciela-Lac-300x200.jpg 300w, https:\/\/cielavillage.fr\/wp-content\/uploads\/2024\/11\/141-Camping-Drome-Lac-Bleu-Ciela-Lac-768x512.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption class=\"wp-element-caption\"><strong>Campeggio Le Lac Bleu<\/strong><\/figcaption><\/figure>\n<\/figure>\n\n<div style=\"height:45px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--2\"><a class=\"wp-block-button__link has-white-color has-text-color has-background has-link-color wp-element-button\" style=\"background-color:#c4d02d\">Scopri i nostri campeggi<\/a><\/div>\n<\/div>\n\n<div style=\"height:45px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\">Le nostre offerte dedicate ai CSE<\/h2>\n\n<p class=\"wp-block-paragraph\">Offriamo diverse formule di <strong>partnership CSE<\/strong>, adatte alle dimensioni della tua organizzazione e al tuo budget.<\/p>\n\n<div class=\"wp-block-columns alignfull has-text-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" style=\"color:#000000;background-color:#ffffff\">\n<div class=\"wp-block-column has-text-color has-link-color wp-elements-06a7fb8c479f13eb979520b28f8cc9d3 is-layout-flow wp-block-column-is-layout-flow\" style=\"color:#0d4245\">\n<p class=\"wp-block-paragraph\" style=\"font-size:24px\">Formula lineare<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una formula flessibile con <strong>tariffe convenzionate<\/strong> a partire da sole 8 settimane. <br\/>Fino al <strong>15% di sconto<\/strong>.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-text-color has-link-color wp-elements-790220d0de893f4637e796b6f76e5b70 is-layout-flow wp-block-column-is-layout-flow\" style=\"color:#0d4245\">\n<p class=\"wp-block-paragraph\" style=\"font-size:24px\">Formula di ripartizione<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Messa a disposizione di alloggi per un determinato periodo con un<br\/><strong>a restituzione<\/strong> delle settimane non vendute.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-text-color has-link-color wp-elements-f01a03521da8ac1629339155b99049bb is-layout-flow wp-block-column-is-layout-flow\" style=\"color:#0d4245\">\n<p class=\"wp-block-paragraph\" style=\"font-size:24px\">Codice sconto<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con il tuo codice CSE, approfitta di <strong>uno sconto del 5% per tutta <\/strong> la stagione nei nostri campeggi.<\/p>\n<\/div>\n<\/div>\n\n<h2 class=\"wp-block-heading\">Strutture per una vacanza indimenticabile<\/h2>\n\n<p class=\"wp-block-paragraph\">I nostri campeggi offrono un ambiente ideale per tutta la famiglia, con strutture e servizi pensati per soddisfare le esigenze di tutti:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Spazi acquatici<\/strong> adatti sia ai pi\u00f9 piccoli che ai pi\u00f9 grandi<\/li>\n\n\n\n<li><strong>Attivit\u00e0 di ogni tipo<\/strong> per tutta la famiglia<\/li>\n\n\n\n<li><strong>Club per bambini (da 5 a 12 anni)<\/strong> in alta stagione<\/li>\n\n\n\n<li><strong>Servizi pratici in loco<\/strong>: ristorazione, negozio di alimentari, biglietteria e molto altro ancora<\/li>\n\n\n\n<li><strong>Alloggi confortevoli e completamente attrezzati<\/strong>, per goderti un soggiorno in tutta tranquillit\u00e0<\/li>\n<\/ul>\n\n<div style=\"height:22px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"801\" height=\"533\" data-id=\"17310\" src=\"https:\/\/cielavillage.fr\/wp-content\/uploads\/2023\/10\/La-terrasse-du-restaurant-du-camping-Au-Lac-de-Biscarrosse-a-Parentis-en-Born.jpg\" alt=\"Campeggio Parentis-en-Born Ciela Village al Lago di Biscarrosse, terrazza del ristorante\" class=\"wp-image-17310\" srcset=\"https:\/\/cielavillage.fr\/wp-content\/uploads\/2023\/10\/La-terrasse-du-restaurant-du-camping-Au-Lac-de-Biscarrosse-a-Parentis-en-Born.jpg 801w, https:\/\/cielavillage.fr\/wp-content\/uploads\/2023\/10\/La-terrasse-du-restaurant-du-camping-Au-Lac-de-Biscarrosse-a-Parentis-en-Born-300x200.jpg 300w, https:\/\/cielavillage.fr\/wp-content\/uploads\/2023\/10\/La-terrasse-du-restaurant-du-camping-Au-Lac-de-Biscarrosse-a-Parentis-en-Born-768x511.jpg 768w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"601\" height=\"400\" data-id=\"24885\" src=\"https:\/\/cielavillage.fr\/wp-content\/uploads\/2024\/10\/235-Camping-Occitanie-Marsouins-Ciela-Village-Club-Enfants.jpg\" alt=\"Campeggio Argel&#xE8;s-sur-Mer Ciela Village Les Marsouins &#x2013; Club per bambini\" class=\"wp-image-24885\" srcset=\"https:\/\/cielavillage.fr\/wp-content\/uploads\/2024\/10\/235-Camping-Occitanie-Marsouins-Ciela-Village-Club-Enfants.jpg 601w, https:\/\/cielavillage.fr\/wp-content\/uploads\/2024\/10\/235-Camping-Occitanie-Marsouins-Ciela-Village-Club-Enfants-300x200.jpg 300w\" sizes=\"(max-width: 601px) 100vw, 601px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"800\" height=\"600\" data-id=\"220007\" src=\"https:\/\/cielavillage.fr\/wp-content\/uploads\/2024\/10\/289_Camping_Vaucluse_Ciela_Village_Avignon_Parc_Hebergement_Ciela_Confort_Luxe_3_Chambres_73.jpg\" alt=\"\" class=\"wp-image-220007\" srcset=\"https:\/\/cielavillage.fr\/wp-content\/uploads\/2024\/10\/289_Camping_Vaucluse_Ciela_Village_Avignon_Parc_Hebergement_Ciela_Confort_Luxe_3_Chambres_73.jpg 800w, https:\/\/cielavillage.fr\/wp-content\/uploads\/2024\/10\/289_Camping_Vaucluse_Ciela_Village_Avignon_Parc_Hebergement_Ciela_Confort_Luxe_3_Chambres_73-300x225.jpg 300w, https:\/\/cielavillage.fr\/wp-content\/uploads\/2024\/10\/289_Camping_Vaucluse_Ciela_Village_Avignon_Parc_Hebergement_Ciela_Confort_Luxe_3_Chambres_73-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/figure>\n\n<div style=\"height:45px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\">Perch\u00e9 scegliere la nostra offerta CSE per il campeggio?<\/h2>\n\n<ul class=\"wp-block-list\">\n<li><strong>Un referente dedicato<\/strong> per accompagnarti durante tutto l&#8217;anno  <\/li>\n\n\n\n<li><strong>Tariffe preferenziali<\/strong> su una selezione di soggiorni e destinazioni  <\/li>\n\n\n\n<li><strong>Vantaggi interessanti<\/strong> per i tuoi dipendenti  <\/li>\n\n\n\n<li><strong>Una partnership flessibile<\/strong>, su misura per le esigenze e le specificit\u00e0 del tuo CSE<\/li>\n<\/ul>\n\n<div style=\"height:45px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\">Il tuo progetto con Ciela Village<\/h2>\n\n\n    \n    \n    \n    <form method=\"post\" novalidate>\n\n        <input type=\"hidden\" id=\"_wpnonce\" name=\"_wpnonce\" value=\"5d18ec4193\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/it\/wp-json\/wp\/v2\/pages\/12661\" \/>        <input type=\"hidden\" name=\"ctv_submitted\" value=\"1\">\n\n        <input\n            class=\"uk-input uk-margin-small\"\n            type=\"text\"\n            name=\"surname\"\n            placeholder=\"Nome dell'azienda : \n\"\n            value=\"\"\n        >\n\n        <input\n            class=\"uk-input uk-margin-small\"\n            type=\"text\"\n            name=\"firstname\"\n            placeholder=\"Cognome & Nome*\"\n            value=\"\"\n            required\n        >\n\n        <input\n            class=\"uk-input uk-margin-small\"\n            type=\"email\"\n            name=\"email\"\n            placeholder=\"Email *\"\n            value=\"\"\n            required\n        >\n\n        <input\n            class=\"uk-input uk-margin-small\"\n            type=\"text\"\n            name=\"phone\"\n            placeholder=\"Numero di telefono\"\n            value=\"\"\n        >\n\n        <input\n            class=\"uk-input uk-margin-small\"\n            type=\"date\"\n            name=\"startdate\"\n            value=\"\"\n            required\n        >\n\n        <input\n            class=\"uk-input uk-margin-small\"\n            type=\"date\"\n            name=\"enddate\"\n            value=\"\"\n            required\n        >\n\n        <input\n            class=\"uk-input uk-margin-small\"\n            type=\"number\"\n            name=\"persons\"\n            value=\"2\"\n            min=\"1\"\n        >\n\n        <textarea\n            class=\"uk-textarea uk-margin-small\"\n            name=\"question\"\n            placeholder=\"Il tuo messaggio\"\n        ><\/textarea>\n\n        <div class=\"uk-margin\">\n            <label>\n                <input type=\"checkbox\" name=\"newsletter\" >\n                Vorrei ricevere la newsletter            <\/label>\n        <\/div>\n\n        <div class=\"uk-margin\">\n            <div class=\"g-recaptcha\" data-sitekey=\"6LfRex4pAAAAABTRhO49dy-2lVsiO-Fd8EnOSBU4\"><\/div>\n        <\/div>\n\n        <div class=\"uk-margin\">\n            <button class=\"uk-button uk-button-primary\" type=\"submit\">\n                Envoyer\n            <\/button>\n        <\/div>\n\n    <\/form>\n\n    \n    \n\n<p class=\"wp-block-paragraph\">Hai bisogno di ulteriori informazioni?<br\/>Il nostro team specializzato \u00e8 al tuo fianco tutto l&#8217;anno per consigliarti e creare offerte su misura che rispondano alle aspettative dei tuoi beneficiari.<\/p>\n\n<p class=\"wp-block-paragraph\">Contattaci: <a href=\"mailto:cse@cielavillage.com\">cse@cielavillage.com<\/a><\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<div style=\"height:45px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\">Si fidano di noi<\/h2>\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-8f761849 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"411\" src=\"https:\/\/cielavillage.fr\/wp-content\/uploads\/2026\/06\/Design-sans-titre-9-1-1024x411.png\" alt=\"Campeggi Ciela Village&#10;: Partner  \" class=\"wp-image-240365\" srcset=\"https:\/\/cielavillage.fr\/wp-content\/uploads\/2026\/06\/Design-sans-titre-9-1-1024x411.png 1024w, https:\/\/cielavillage.fr\/wp-content\/uploads\/2026\/06\/Design-sans-titre-9-1-300x120.png 300w, https:\/\/cielavillage.fr\/wp-content\/uploads\/2026\/06\/Design-sans-titre-9-1-768x308.png 768w, https:\/\/cielavillage.fr\/wp-content\/uploads\/2026\/06\/Design-sans-titre-9-1-1536x617.png 1536w, https:\/\/cielavillage.fr\/wp-content\/uploads\/2026\/06\/Design-sans-titre-9-1.png 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Regala ai tuoi collaboratori una vacanza indimenticabile! Vuoi proporre ai tuoi dipendenti un&#8217;offerta vacanze interessante a tariffe agevolate? Ciela Village affianca i Comitati Sociali ed Economici (CSE), i COS e le associazioni del personale nell&#8217;organizzazione di offerte vacanze interessanti per i loro dipendenti e beneficiari. Con 24 campeggi da 3 a 5 stelle, situati in [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-12661","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Scopri le nostre offerte CSE - Ciela Village<\/title>\n<meta name=\"description\" content=\"Offerte CSE: approfitta di proposte su misura per la tua azienda. Un team commerciale \u00e8 a tua disposizione per soddisfare le tue esigenze. Scopri di pi\u00f9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cielavillage.fr\/it\/offerte-campeggi-per-comitati-aziendali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Scopri le nostre offerte CSE - Ciela Village\" \/>\n<meta property=\"og:description\" content=\"Offerte CSE: approfitta di proposte su misura per la tua azienda. Un team commerciale \u00e8 a tua disposizione per soddisfare le tue esigenze. Scopri di pi\u00f9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cielavillage.fr\/it\/offerte-campeggi-per-comitati-aziendali\/\" \/>\n<meta property=\"og:site_name\" content=\"Ciela Village\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-03T11:28:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cielavillage.fr\/wp-content\/uploads\/2023\/10\/Le-parc-aquatique-du-camping-Terra-Verdon-a-Castellane.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cielavillage.fr\\\/it\\\/offerte-campeggi-per-comitati-aziendali\\\/\",\"url\":\"https:\\\/\\\/cielavillage.fr\\\/it\\\/offerte-campeggi-per-comitati-aziendali\\\/\",\"name\":\"Scopri le nostre offerte CSE - Ciela Village\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cielavillage.fr\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cielavillage.fr\\\/it\\\/offerte-campeggi-per-comitati-aziendali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cielavillage.fr\\\/it\\\/offerte-campeggi-per-comitati-aziendali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cielavillage.fr\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Le-parc-aquatique-du-camping-Terra-Verdon-a-Castellane.jpg\",\"datePublished\":\"2022-06-10T08:50:47+00:00\",\"dateModified\":\"2026-07-03T11:28:04+00:00\",\"description\":\"Offerte CSE: approfitta di proposte su misura per la tua azienda. Un team commerciale \u00e8 a tua disposizione per soddisfare le tue esigenze. Scopri di pi\u00f9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cielavillage.fr\\\/it\\\/offerte-campeggi-per-comitati-aziendali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cielavillage.fr\\\/it\\\/offerte-campeggi-per-comitati-aziendali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cielavillage.fr\\\/it\\\/offerte-campeggi-per-comitati-aziendali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cielavillage.fr\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Le-parc-aquatique-du-camping-Terra-Verdon-a-Castellane.jpg\",\"contentUrl\":\"https:\\\/\\\/cielavillage.fr\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Le-parc-aquatique-du-camping-Terra-Verdon-a-Castellane.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cielavillage.fr\\\/it\\\/offerte-campeggi-per-comitati-aziendali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Ciela Village\",\"item\":\"https:\\\/\\\/cielavillage.fr\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Scopri le nostre offerte CSE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cielavillage.fr\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/cielavillage.fr\\\/it\\\/\",\"name\":\"Ciela Village\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cielavillage.fr\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Scopri le nostre offerte CSE - Ciela Village","description":"Offerte CSE: approfitta di proposte su misura per la tua azienda. Un team commerciale \u00e8 a tua disposizione per soddisfare le tue esigenze. Scopri di pi\u00f9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cielavillage.fr\/it\/offerte-campeggi-per-comitati-aziendali\/","og_locale":"it_IT","og_type":"article","og_title":"Scopri le nostre offerte CSE - Ciela Village","og_description":"Offerte CSE: approfitta di proposte su misura per la tua azienda. Un team commerciale \u00e8 a tua disposizione per soddisfare le tue esigenze. Scopri di pi\u00f9.","og_url":"https:\/\/cielavillage.fr\/it\/offerte-campeggi-per-comitati-aziendali\/","og_site_name":"Ciela Village","article_modified_time":"2026-07-03T11:28:04+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/cielavillage.fr\/wp-content\/uploads\/2023\/10\/Le-parc-aquatique-du-camping-Terra-Verdon-a-Castellane.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cielavillage.fr\/it\/offerte-campeggi-per-comitati-aziendali\/","url":"https:\/\/cielavillage.fr\/it\/offerte-campeggi-per-comitati-aziendali\/","name":"Scopri le nostre offerte CSE - Ciela Village","isPartOf":{"@id":"https:\/\/cielavillage.fr\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cielavillage.fr\/it\/offerte-campeggi-per-comitati-aziendali\/#primaryimage"},"image":{"@id":"https:\/\/cielavillage.fr\/it\/offerte-campeggi-per-comitati-aziendali\/#primaryimage"},"thumbnailUrl":"https:\/\/cielavillage.fr\/wp-content\/uploads\/2023\/10\/Le-parc-aquatique-du-camping-Terra-Verdon-a-Castellane.jpg","datePublished":"2022-06-10T08:50:47+00:00","dateModified":"2026-07-03T11:28:04+00:00","description":"Offerte CSE: approfitta di proposte su misura per la tua azienda. Un team commerciale \u00e8 a tua disposizione per soddisfare le tue esigenze. Scopri di pi\u00f9.","breadcrumb":{"@id":"https:\/\/cielavillage.fr\/it\/offerte-campeggi-per-comitati-aziendali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cielavillage.fr\/it\/offerte-campeggi-per-comitati-aziendali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cielavillage.fr\/it\/offerte-campeggi-per-comitati-aziendali\/#primaryimage","url":"https:\/\/cielavillage.fr\/wp-content\/uploads\/2023\/10\/Le-parc-aquatique-du-camping-Terra-Verdon-a-Castellane.jpg","contentUrl":"https:\/\/cielavillage.fr\/wp-content\/uploads\/2023\/10\/Le-parc-aquatique-du-camping-Terra-Verdon-a-Castellane.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cielavillage.fr\/it\/offerte-campeggi-per-comitati-aziendali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Ciela Village","item":"https:\/\/cielavillage.fr\/it\/"},{"@type":"ListItem","position":2,"name":"Scopri le nostre offerte CSE"}]},{"@type":"WebSite","@id":"https:\/\/cielavillage.fr\/it\/#website","url":"https:\/\/cielavillage.fr\/it\/","name":"Ciela Village","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cielavillage.fr\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/cielavillage.fr\/it\/wp-json\/wp\/v2\/pages\/12661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cielavillage.fr\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cielavillage.fr\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cielavillage.fr\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cielavillage.fr\/it\/wp-json\/wp\/v2\/comments?post=12661"}],"version-history":[{"count":3,"href":"https:\/\/cielavillage.fr\/it\/wp-json\/wp\/v2\/pages\/12661\/revisions"}],"predecessor-version":[{"id":291246,"href":"https:\/\/cielavillage.fr\/it\/wp-json\/wp\/v2\/pages\/12661\/revisions\/291246"}],"wp:attachment":[{"href":"https:\/\/cielavillage.fr\/it\/wp-json\/wp\/v2\/media?parent=12661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}